{"id":32260,"date":"2017-05-16T18:54:37","date_gmt":"2017-05-16T16:54:37","guid":{"rendered":"https:\/\/www.gotobrno.live\/brno-prakticky\/doprava\/"},"modified":"2026-06-15T13:56:58","modified_gmt":"2026-06-15T11:56:58","slug":"verkehr","status":"publish","type":"page","link":"https:\/\/www.gotobrno.live\/de\/bruenn-praktisch\/verkehr\/","title":{"rendered":"Verkehr"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"Wie gelangt man von Punkt A&nbsp;nach Punkt B? N\u00fctzliche Links und Informationen zum \u00f6ffentlichen Nah- und Regionalverkehr sowie zu Auto, Rad und Parkm\u00f6glichkeiten in Br\u00fcnn","protected":false},"author":13,"featured_media":32261,"parent":32248,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template-transport.php","meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.gotobrno.live\/de\/wp-json\/wp\/v2\/pages\/32260"}],"collection":[{"href":"https:\/\/www.gotobrno.live\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.gotobrno.live\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.gotobrno.live\/de\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/www.gotobrno.live\/de\/wp-json\/wp\/v2\/comments?post=32260"}],"version-history":[{"count":2,"href":"https:\/\/www.gotobrno.live\/de\/wp-json\/wp\/v2\/pages\/32260\/revisions"}],"predecessor-version":[{"id":312440,"href":"https:\/\/www.gotobrno.live\/de\/wp-json\/wp\/v2\/pages\/32260\/revisions\/312440"}],"up":[{"embeddable":true,"href":"https:\/\/www.gotobrno.live\/de\/wp-json\/wp\/v2\/pages\/32248"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.gotobrno.live\/de\/wp-json\/wp\/v2\/media\/32261"}],"wp:attachment":[{"href":"https:\/\/www.gotobrno.live\/de\/wp-json\/wp\/v2\/media?parent=32260"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}